{"id":113904,"date":"2025-06-19T08:00:12","date_gmt":"2025-06-19T06:00:12","guid":{"rendered":"https:\/\/www.matrix4design.com\/?p=113904"},"modified":"2025-06-16T16:38:26","modified_gmt":"2025-06-16T14:38:26","slug":"il-nuovo-hub-milanese-di-deloitte-firmato-lombardini22","status":"publish","type":"post","link":"https:\/\/www.matrix4design.com\/it\/architettura\/il-nuovo-hub-milanese-di-deloitte-firmato-lombardini22\/","title":{"rendered":"Il nuovo hub milanese di Deloitte firmato Lombardini22"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>Dopo aver curato il progetto della sede romana della societ\u00e0,<a href=\"https:\/\/www.lombardini22.com\/\" target=\"_blank\" rel=\"noopener\"><strong> Lombardini22<\/strong> <\/a>riprende la relazione con <strong>Deloitte <\/strong>per progettarne il nuovo <strong>headquarter milanese <\/strong>in via Santa Sofia 28.<\/p>\n<p>Pensato come un <strong>hub<\/strong> piuttosto che come un tradizionale ufficio, il nuovo headquarter interpreta le esigenze di <strong>flessibilit\u00e0<\/strong> e <strong>collaborazione<\/strong> che definiscono il lavoro contemporaneo.<\/p>\n<p>Gli spazi sono stati progettati con un modello ad alto tasso di condivisione: 1.889 postazioni di lavoro organizzate in un <strong>layout fluido<\/strong> che incoraggia l\u2019interazione e la socialit\u00e0. Ad esse si aggiungono aree per il lavoro di squadra, un auditorium, una food court ipogea e persino un\u2019area clienti al quinto piano, con uno spazio lounge e catering.<\/p>\n<p>Elemento identitario del campus \u00e8 la <strong>Chiesa sconsacrata di San Paolo Converso<\/strong>, risalente al XVI secolo, che \u00e8 stata valorizzata attraverso un attento progetto di allestimento firmato da <strong>DEGW<\/strong>, business unit di Lombardini22. Oggi questo spazio, mantenendo intatto il suo impianto storico e decorativo originario, \u00e8 destinato a eventi, esposizioni e incontri con i clienti, con accesso sia da piazza Sant\u2019Eufemia sia da un nuovo ingresso secondario dal cuore del campus. Un dialogo tra storia e funzione che rafforza il senso di <strong>appartenenza<\/strong> e <strong>rappresentativit\u00e0<\/strong> del luogo.<\/p>\n<p><strong>La piazza centrale<\/strong> rappresenta il vero fulcro dell\u2019hub Deloitte, da cui si diramano le workstation e le altre aree operative. Tecnologie avanzate e soluzioni ergonomiche garantiscono il massimo comfort e funzionalit\u00e0; postazioni prenotabili, lockers intelligenti e strumenti di lavoro all\u2019avanguardia offrono un\u2019esperienza fluida e integrata.<\/p>\n<p>Tra gli spazi dedicati all\u2019innovazione, il <strong>Generative AI Studio<\/strong> (Solaria Space) si presenta come un vero e proprio laboratorio d\u2019innovazione, pensato per esplorare e mostrare le potenzialit\u00e0 delle nuove tecnologie legate all\u2019Intelligenza Artificiale. Progettato per offrire un\u2019<strong>esperienza<\/strong> <strong>immersiva<\/strong> a clienti, partner e stakeholder, l\u2019ambiente \u00e8 caratterizzato da un design su misura che unisce elementi architettonici distintivi, giochi di luce e cromie dinamiche.<\/p>\n<p>L\u2019attenzione alla sostenibilit\u00e0 e alla qualit\u00e0 dei materiali utilizzati risulta fondamentale per il processo di raggiungimento delle certificazioni di sostenibilit\u00e0: <strong>LEED Platinum<\/strong> e <strong>WELL Gold<\/strong>. Le scelte illuminotecniche sono state studiate in collaborazione con <strong>Allianz<\/strong>, mentre Lombardini22 ha curato anche la segnaletica e l\u2019identit\u00e0 visiva degli spazi.<\/p>\n<p>Gli ambienti si distinguono infine per una <strong>progettazione acustica<\/strong> di alto livello e per la presenza di aree innovative come <strong>studios<\/strong>, <strong>zone mindfulness<\/strong> per yoga e pilates, e spazi di lavoro satelliti per training e meeting.<\/p>\n<p>&nbsp;<\/p>\n\t\t<div style=\"clear:both\"><\/div>\n\t\t<div class=\"psgal_wrap\">\n\t\t\t<div id=\"psgal_113904_1\" data-psgal_id=\"113904_1\" data-psgal_container_id=\"container_113904_1\" data-psgal_thumbnail_width=\"164\" data-psgal_use_masonary=\"1\" class=\"psgal-inline psgal gallery-columns-3 gallery-size-thumbnail use_masonry_1 show_captions_\" itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\">\n\t\t\t\t\t\t\t\t\t\t<figure class=\"msnry_items\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" style=\"width:164px;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2025\/06\/Spazi-Deloitte-Milano-003-_Lombardini22_-@Carola-Merello.jpg\" itemprop=\"contentUrl\" data-size=\"1500x1182\" data-caption=\"\u00a9 Carola Merello\" style=\"height:154px;\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"msnry_thumb\" src=\"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2025\/06\/Spazi-Deloitte-Milano-003-_Lombardini22_-@Carola-Merello-328x328.jpg\" itemprop=\"thumbnail\" alt=\"\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"photoswipe-gallery-caption\" style=\"display:none;\">\u00a9 Carola Merello<\/figcaption>\n\n\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t\t<figure class=\"msnry_items\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" style=\"width:164px;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2025\/06\/Spazi-Deloitte-Milano-004_Lombardini22_-@Carola-Merello.jpg\" itemprop=\"contentUrl\" data-size=\"1500x1209\" data-caption=\"\u00a9 Carola Merello\" style=\"height:154px;\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"msnry_thumb\" src=\"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2025\/06\/Spazi-Deloitte-Milano-004_Lombardini22_-@Carola-Merello-328x328.jpg\" itemprop=\"thumbnail\" alt=\"\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"photoswipe-gallery-caption\" style=\"display:none;\">\u00a9 Carola Merello<\/figcaption>\n\n\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t\t<figure class=\"msnry_items\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" style=\"width:164px;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2025\/06\/Spazi-Deloitte-Milano-009-_Lombardini22_-@Carola-Merello.jpg\" itemprop=\"contentUrl\" data-size=\"1500x1398\" data-caption=\"\u00a9 Carola Merello\" style=\"height:154px;\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"msnry_thumb\" src=\"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2025\/06\/Spazi-Deloitte-Milano-009-_Lombardini22_-@Carola-Merello-328x328.jpg\" itemprop=\"thumbnail\" alt=\"\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"photoswipe-gallery-caption\" style=\"display:none;\">\u00a9 Carola Merello<\/figcaption>\n\n\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t\t<figure class=\"msnry_items\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" style=\"width:164px;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2025\/06\/Spazi-Deloitte-Milano-012_Lombardini22_-@Carola-Merello.jpg\" itemprop=\"contentUrl\" data-size=\"1380x1500\" data-caption=\"\u00a9 Carola Merello\" style=\"height:154px;\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"msnry_thumb\" src=\"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2025\/06\/Spazi-Deloitte-Milano-012_Lombardini22_-@Carola-Merello-328x328.jpg\" itemprop=\"thumbnail\" alt=\"\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"photoswipe-gallery-caption\" style=\"display:none;\">\u00a9 Carola Merello<\/figcaption>\n\n\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t\t<figure class=\"msnry_items\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" style=\"width:164px;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2025\/06\/Spazi-Deloitte-Milano-013_Lombardini22_-@Carola-Merello.jpg\" itemprop=\"contentUrl\" data-size=\"1298x1500\" data-caption=\"\u00a9 Carola Merello\" style=\"height:154px;\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"msnry_thumb\" src=\"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2025\/06\/Spazi-Deloitte-Milano-013_Lombardini22_-@Carola-Merello-328x328.jpg\" itemprop=\"thumbnail\" alt=\"\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"photoswipe-gallery-caption\" style=\"display:none;\">\u00a9 Carola Merello<\/figcaption>\n\n\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t\t<figure class=\"msnry_items\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" style=\"width:164px;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2025\/06\/Spazi-Deloitte-Milano-023_Lombardini22_-@Carola-Merello.jpg\" itemprop=\"contentUrl\" data-size=\"1500x1279\" data-caption=\"\u00a9 Carola Merello\" style=\"height:154px;\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"msnry_thumb\" src=\"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2025\/06\/Spazi-Deloitte-Milano-023_Lombardini22_-@Carola-Merello-328x328.jpg\" itemprop=\"thumbnail\" alt=\"\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"photoswipe-gallery-caption\" style=\"display:none;\">\u00a9 Carola Merello<\/figcaption>\n\n\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t\t<figure class=\"msnry_items\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" style=\"width:164px;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2025\/06\/Spazi-Deloitte-Milano-041_Lombardini22_-@Carola-Merello.jpg\" itemprop=\"contentUrl\" data-size=\"1290x1500\" data-caption=\"\u00a9 Carola Merello\" style=\"height:154px;\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"msnry_thumb\" src=\"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2025\/06\/Spazi-Deloitte-Milano-041_Lombardini22_-@Carola-Merello-328x328.jpg\" itemprop=\"thumbnail\" alt=\"\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"photoswipe-gallery-caption\" style=\"display:none;\">\u00a9 Carola Merello<\/figcaption>\n\n\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t\t<figure class=\"msnry_items\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" style=\"width:164px;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2025\/06\/Spazi-Deloitte-Milano-051_Lombardini22_-@Carola-Merello.jpg\" itemprop=\"contentUrl\" data-size=\"1500x1241\" data-caption=\"\u00a9 Carola Merello\" style=\"height:154px;\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"msnry_thumb\" src=\"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2025\/06\/Spazi-Deloitte-Milano-051_Lombardini22_-@Carola-Merello-328x328.jpg\" itemprop=\"thumbnail\" alt=\"\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"photoswipe-gallery-caption\" style=\"display:none;\">\u00a9 Carola Merello<\/figcaption>\n\n\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t\t<figure class=\"msnry_items\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" style=\"width:164px;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2025\/06\/Spazi-Deloitte-Milano-056-_Lombardini22_-@Carola-Merello.jpg\" itemprop=\"contentUrl\" data-size=\"1500x1167\" data-caption=\"\u00a9 Carola Merello\" style=\"height:154px;\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"msnry_thumb\" src=\"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2025\/06\/Spazi-Deloitte-Milano-056-_Lombardini22_-@Carola-Merello-328x328.jpg\" itemprop=\"thumbnail\" alt=\"\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"photoswipe-gallery-caption\" style=\"display:none;\">\u00a9 Carola Merello<\/figcaption>\n\n\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t\t<figure class=\"msnry_items\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" style=\"width:164px;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2025\/06\/Spazi-Deloitte-Milano-059-_Lombardini22_-@Carola-Merello.jpg\" itemprop=\"contentUrl\" data-size=\"1500x1151\" data-caption=\"\u00a9 Carola Merello\" style=\"height:154px;\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"msnry_thumb\" src=\"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2025\/06\/Spazi-Deloitte-Milano-059-_Lombardini22_-@Carola-Merello-328x328.jpg\" itemprop=\"thumbnail\" alt=\"\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"photoswipe-gallery-caption\" style=\"display:none;\">\u00a9 Carola Merello<\/figcaption>\n\n\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t\t<figure class=\"msnry_items\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" style=\"width:164px;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2025\/06\/Spazi-Deloitte-Milano026_Lombardini22_-@Carola-Merello.jpg\" itemprop=\"contentUrl\" data-size=\"1500x1270\" data-caption=\"\u00a9 Carola Merello\" style=\"height:154px;\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"msnry_thumb\" src=\"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2025\/06\/Spazi-Deloitte-Milano026_Lombardini22_-@Carola-Merello-328x328.jpg\" itemprop=\"thumbnail\" alt=\"\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"photoswipe-gallery-caption\" style=\"display:none;\">\u00a9 Carola Merello<\/figcaption>\n\n\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t\t<figure class=\"msnry_items\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" style=\"width:164px;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2025\/06\/Spazi-Deloitte-Milano061_Lombardini22_-@Carola-Merello.jpg\" itemprop=\"contentUrl\" data-size=\"1500x1169\" data-caption=\"\u00a9 Carola Merello\" style=\"height:154px;\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"msnry_thumb\" src=\"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2025\/06\/Spazi-Deloitte-Milano061_Lombardini22_-@Carola-Merello-328x328.jpg\" itemprop=\"thumbnail\" alt=\"\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"photoswipe-gallery-caption\" style=\"display:none;\">\u00a9 Carola Merello<\/figcaption>\n\n\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div style='clear:both'><\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Dopo aver curato il progetto della sede romana della societ\u00e0, Lombardini22 riprende la relazione con Deloitte per progettarne il nuovo headquarter milanese in via Santa Sofia 28. Pensato come un hub piuttosto che come un tradizionale ufficio, il nuovo headquarter interpreta le esigenze di flessibilit\u00e0 e collaborazione che definiscono il lavoro contemporaneo. Gli spazi [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":113905,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[367,417,368],"tags":[],"class_list":{"0":"post-113904","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-architettura","8":"category-architettura-home","9":"category-featured"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il nuovo hub milanese di Deloitte firmato Lombardini22<\/title>\n<meta name=\"description\" content=\"Dopo aver curato il progetto della sede romana della societ\u00e0, Lombardini22 riprende la relazione con Deloitte per progettarne il nuovo headquarter milanese in via Santa Sofia 28.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.matrix4design.com\/it\/architettura\/il-nuovo-hub-milanese-di-deloitte-firmato-lombardini22\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il nuovo hub milanese di Deloitte firmato Lombardini22\" \/>\n<meta property=\"og:description\" content=\"Dopo aver curato il progetto della sede romana della societ\u00e0, Lombardini22 riprende la relazione con Deloitte per progettarne il nuovo headquarter milanese in via Santa Sofia 28.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.matrix4design.com\/it\/architettura\/il-nuovo-hub-milanese-di-deloitte-firmato-lombardini22\/\" \/>\n<meta property=\"og:site_name\" content=\"Matrix4Design\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/matrix4designmagazine\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-19T06:00:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2025\/06\/Spazi-Deloitte-Milano056_Lombardini22_-Carola-Merello.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1167\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.matrix4design.com\/it\/architettura\/il-nuovo-hub-milanese-di-deloitte-firmato-lombardini22\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.matrix4design.com\/it\/architettura\/il-nuovo-hub-milanese-di-deloitte-firmato-lombardini22\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\/\/www.matrix4design.com\/it\/#\/schema\/person\/b2b6dd48f9d6892ca224742379951fa1\"},\"headline\":\"Il nuovo hub milanese di Deloitte firmato Lombardini22\",\"datePublished\":\"2025-06-19T06:00:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.matrix4design.com\/it\/architettura\/il-nuovo-hub-milanese-di-deloitte-firmato-lombardini22\/\"},\"wordCount\":405,\"publisher\":{\"@id\":\"https:\/\/www.matrix4design.com\/it\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.matrix4design.com\/it\/architettura\/il-nuovo-hub-milanese-di-deloitte-firmato-lombardini22\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2025\/06\/Spazi-Deloitte-Milano056_Lombardini22_-Carola-Merello.jpg\",\"articleSection\":[\"Architettura\",\"Architettura home\",\"Featured\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.matrix4design.com\/it\/architettura\/il-nuovo-hub-milanese-di-deloitte-firmato-lombardini22\/\",\"url\":\"https:\/\/www.matrix4design.com\/it\/architettura\/il-nuovo-hub-milanese-di-deloitte-firmato-lombardini22\/\",\"name\":\"Il nuovo hub milanese di Deloitte firmato Lombardini22\",\"isPartOf\":{\"@id\":\"https:\/\/www.matrix4design.com\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.matrix4design.com\/it\/architettura\/il-nuovo-hub-milanese-di-deloitte-firmato-lombardini22\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.matrix4design.com\/it\/architettura\/il-nuovo-hub-milanese-di-deloitte-firmato-lombardini22\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2025\/06\/Spazi-Deloitte-Milano056_Lombardini22_-Carola-Merello.jpg\",\"datePublished\":\"2025-06-19T06:00:12+00:00\",\"description\":\"Dopo aver curato il progetto della sede romana della societ\u00e0, Lombardini22 riprende la relazione con Deloitte per progettarne il nuovo headquarter milanese in via Santa Sofia 28.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.matrix4design.com\/it\/architettura\/il-nuovo-hub-milanese-di-deloitte-firmato-lombardini22\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.matrix4design.com\/it\/architettura\/il-nuovo-hub-milanese-di-deloitte-firmato-lombardini22\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.matrix4design.com\/it\/architettura\/il-nuovo-hub-milanese-di-deloitte-firmato-lombardini22\/#primaryimage\",\"url\":\"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2025\/06\/Spazi-Deloitte-Milano056_Lombardini22_-Carola-Merello.jpg\",\"contentUrl\":\"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2025\/06\/Spazi-Deloitte-Milano056_Lombardini22_-Carola-Merello.jpg\",\"width\":1500,\"height\":1167},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.matrix4design.com\/it\/architettura\/il-nuovo-hub-milanese-di-deloitte-firmato-lombardini22\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.matrix4design.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il nuovo hub milanese di Deloitte firmato Lombardini22\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.matrix4design.com\/it\/#website\",\"url\":\"https:\/\/www.matrix4design.com\/it\/\",\"name\":\"Matrix4Design\",\"description\":\"Digital architecture and design b2b magazine\",\"publisher\":{\"@id\":\"https:\/\/www.matrix4design.com\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.matrix4design.com\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.matrix4design.com\/it\/#organization\",\"name\":\"Matrix4Design\",\"url\":\"https:\/\/www.matrix4design.com\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.matrix4design.com\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2020\/04\/logo_matrix4design.png\",\"contentUrl\":\"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2020\/04\/logo_matrix4design.png\",\"width\":804,\"height\":114,\"caption\":\"Matrix4Design\"},\"image\":{\"@id\":\"https:\/\/www.matrix4design.com\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/matrix4designmagazine\/\",\"https:\/\/www.instagram.com\/matrix4designmagazine\/\",\"https:\/\/www.youtube.com\/channel\/UCtuhSSrP3MOO_URZgv8mQ1A\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.matrix4design.com\/it\/#\/schema\/person\/b2b6dd48f9d6892ca224742379951fa1\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.matrix4design.com\/it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2023\/01\/logo_M4D_2023-96x96.jpg\",\"contentUrl\":\"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2023\/01\/logo_M4D_2023-96x96.jpg\",\"caption\":\"Redazione\"},\"url\":\"https:\/\/www.matrix4design.com\/it\/author\/redazione\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il nuovo hub milanese di Deloitte firmato Lombardini22","description":"Dopo aver curato il progetto della sede romana della societ\u00e0, Lombardini22 riprende la relazione con Deloitte per progettarne il nuovo headquarter milanese in via Santa Sofia 28.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.matrix4design.com\/it\/architettura\/il-nuovo-hub-milanese-di-deloitte-firmato-lombardini22\/","og_locale":"it_IT","og_type":"article","og_title":"Il nuovo hub milanese di Deloitte firmato Lombardini22","og_description":"Dopo aver curato il progetto della sede romana della societ\u00e0, Lombardini22 riprende la relazione con Deloitte per progettarne il nuovo headquarter milanese in via Santa Sofia 28.","og_url":"https:\/\/www.matrix4design.com\/it\/architettura\/il-nuovo-hub-milanese-di-deloitte-firmato-lombardini22\/","og_site_name":"Matrix4Design","article_publisher":"https:\/\/www.facebook.com\/matrix4designmagazine\/","article_published_time":"2025-06-19T06:00:12+00:00","og_image":[{"width":1500,"height":1167,"url":"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2025\/06\/Spazi-Deloitte-Milano056_Lombardini22_-Carola-Merello.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.matrix4design.com\/it\/architettura\/il-nuovo-hub-milanese-di-deloitte-firmato-lombardini22\/#article","isPartOf":{"@id":"https:\/\/www.matrix4design.com\/it\/architettura\/il-nuovo-hub-milanese-di-deloitte-firmato-lombardini22\/"},"author":{"name":"Redazione","@id":"https:\/\/www.matrix4design.com\/it\/#\/schema\/person\/b2b6dd48f9d6892ca224742379951fa1"},"headline":"Il nuovo hub milanese di Deloitte firmato Lombardini22","datePublished":"2025-06-19T06:00:12+00:00","mainEntityOfPage":{"@id":"https:\/\/www.matrix4design.com\/it\/architettura\/il-nuovo-hub-milanese-di-deloitte-firmato-lombardini22\/"},"wordCount":405,"publisher":{"@id":"https:\/\/www.matrix4design.com\/it\/#organization"},"image":{"@id":"https:\/\/www.matrix4design.com\/it\/architettura\/il-nuovo-hub-milanese-di-deloitte-firmato-lombardini22\/#primaryimage"},"thumbnailUrl":"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2025\/06\/Spazi-Deloitte-Milano056_Lombardini22_-Carola-Merello.jpg","articleSection":["Architettura","Architettura home","Featured"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.matrix4design.com\/it\/architettura\/il-nuovo-hub-milanese-di-deloitte-firmato-lombardini22\/","url":"https:\/\/www.matrix4design.com\/it\/architettura\/il-nuovo-hub-milanese-di-deloitte-firmato-lombardini22\/","name":"Il nuovo hub milanese di Deloitte firmato Lombardini22","isPartOf":{"@id":"https:\/\/www.matrix4design.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.matrix4design.com\/it\/architettura\/il-nuovo-hub-milanese-di-deloitte-firmato-lombardini22\/#primaryimage"},"image":{"@id":"https:\/\/www.matrix4design.com\/it\/architettura\/il-nuovo-hub-milanese-di-deloitte-firmato-lombardini22\/#primaryimage"},"thumbnailUrl":"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2025\/06\/Spazi-Deloitte-Milano056_Lombardini22_-Carola-Merello.jpg","datePublished":"2025-06-19T06:00:12+00:00","description":"Dopo aver curato il progetto della sede romana della societ\u00e0, Lombardini22 riprende la relazione con Deloitte per progettarne il nuovo headquarter milanese in via Santa Sofia 28.","breadcrumb":{"@id":"https:\/\/www.matrix4design.com\/it\/architettura\/il-nuovo-hub-milanese-di-deloitte-firmato-lombardini22\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.matrix4design.com\/it\/architettura\/il-nuovo-hub-milanese-di-deloitte-firmato-lombardini22\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.matrix4design.com\/it\/architettura\/il-nuovo-hub-milanese-di-deloitte-firmato-lombardini22\/#primaryimage","url":"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2025\/06\/Spazi-Deloitte-Milano056_Lombardini22_-Carola-Merello.jpg","contentUrl":"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2025\/06\/Spazi-Deloitte-Milano056_Lombardini22_-Carola-Merello.jpg","width":1500,"height":1167},{"@type":"BreadcrumbList","@id":"https:\/\/www.matrix4design.com\/it\/architettura\/il-nuovo-hub-milanese-di-deloitte-firmato-lombardini22\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.matrix4design.com\/it\/"},{"@type":"ListItem","position":2,"name":"Il nuovo hub milanese di Deloitte firmato Lombardini22"}]},{"@type":"WebSite","@id":"https:\/\/www.matrix4design.com\/it\/#website","url":"https:\/\/www.matrix4design.com\/it\/","name":"Matrix4Design","description":"Digital architecture and design b2b magazine","publisher":{"@id":"https:\/\/www.matrix4design.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.matrix4design.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.matrix4design.com\/it\/#organization","name":"Matrix4Design","url":"https:\/\/www.matrix4design.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.matrix4design.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2020\/04\/logo_matrix4design.png","contentUrl":"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2020\/04\/logo_matrix4design.png","width":804,"height":114,"caption":"Matrix4Design"},"image":{"@id":"https:\/\/www.matrix4design.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/matrix4designmagazine\/","https:\/\/www.instagram.com\/matrix4designmagazine\/","https:\/\/www.youtube.com\/channel\/UCtuhSSrP3MOO_URZgv8mQ1A"]},{"@type":"Person","@id":"https:\/\/www.matrix4design.com\/it\/#\/schema\/person\/b2b6dd48f9d6892ca224742379951fa1","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.matrix4design.com\/it\/#\/schema\/person\/image\/","url":"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2023\/01\/logo_M4D_2023-96x96.jpg","contentUrl":"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2023\/01\/logo_M4D_2023-96x96.jpg","caption":"Redazione"},"url":"https:\/\/www.matrix4design.com\/it\/author\/redazione\/"}]}},"_links":{"self":[{"href":"https:\/\/www.matrix4design.com\/it\/wp-json\/wp\/v2\/posts\/113904","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.matrix4design.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.matrix4design.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.matrix4design.com\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.matrix4design.com\/it\/wp-json\/wp\/v2\/comments?post=113904"}],"version-history":[{"count":3,"href":"https:\/\/www.matrix4design.com\/it\/wp-json\/wp\/v2\/posts\/113904\/revisions"}],"predecessor-version":[{"id":113921,"href":"https:\/\/www.matrix4design.com\/it\/wp-json\/wp\/v2\/posts\/113904\/revisions\/113921"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.matrix4design.com\/it\/wp-json\/wp\/v2\/media\/113905"}],"wp:attachment":[{"href":"https:\/\/www.matrix4design.com\/it\/wp-json\/wp\/v2\/media?parent=113904"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.matrix4design.com\/it\/wp-json\/wp\/v2\/categories?post=113904"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.matrix4design.com\/it\/wp-json\/wp\/v2\/tags?post=113904"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}