{"id":116934,"date":"2025-11-21T08:00:26","date_gmt":"2025-11-21T07:00:26","guid":{"rendered":"https:\/\/www.matrix4design.com\/?p=116934"},"modified":"2025-11-20T09:33:30","modified_gmt":"2025-11-20T08:33:30","slug":"flos-e-ronan-bouroullec-la-poesia-della-luce-sospesa-tra-sfera-e-cilindro","status":"publish","type":"post","link":"https:\/\/www.matrix4design.com\/it\/design\/flos-e-ronan-bouroullec-la-poesia-della-luce-sospesa-tra-sfera-e-cilindro\/","title":{"rendered":"Flos e Ronan Bouroullec: la poesia della luce sospesa tra sfera e cilindro"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><strong>Ronan Bouroullec<\/strong> firma per<a href=\"https:\/\/flos.com\/it\/it\/\" target=\"_blank\" rel=\"noopener\"><strong> Flos<\/strong><\/a> due nuove lampade a sospensione modulari, <strong>Luce Sferica<\/strong> e <strong>Luce Cilindrica<\/strong>, uscite nel 2025. Questi progetti non sono semplici corpi illuminanti, ma vere e proprie esaltazioni della <strong>bellezza delle cose semplici<\/strong> e della magia ottenuta attraverso la raffinatezza tecnica. Il design mira a unire la bellezza poetica del prodotto artigianale a un&#8217;anima industriale e funzionale.<\/p>\n<figure id=\"attachment_116936\" aria-describedby=\"caption-attachment-116936\" style=\"width: 1200px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-116936\" src=\"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2025\/11\/Flos-Luce_Sferica-PH_Robert_Rieger-2025-002.19532e93.jpg\" alt=\"\" width=\"1200\" height=\"1600\" srcset=\"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2025\/11\/Flos-Luce_Sferica-PH_Robert_Rieger-2025-002.19532e93.jpg 1200w, https:\/\/www.matrix4design.com\/wp-content\/uploads\/2025\/11\/Flos-Luce_Sferica-PH_Robert_Rieger-2025-002.19532e93-225x300.jpg 225w, https:\/\/www.matrix4design.com\/wp-content\/uploads\/2025\/11\/Flos-Luce_Sferica-PH_Robert_Rieger-2025-002.19532e93-768x1024.jpg 768w, https:\/\/www.matrix4design.com\/wp-content\/uploads\/2025\/11\/Flos-Luce_Sferica-PH_Robert_Rieger-2025-002.19532e93-1152x1536.jpg 1152w, https:\/\/www.matrix4design.com\/wp-content\/uploads\/2025\/11\/Flos-Luce_Sferica-PH_Robert_Rieger-2025-002.19532e93-150x200.jpg 150w, https:\/\/www.matrix4design.com\/wp-content\/uploads\/2025\/11\/Flos-Luce_Sferica-PH_Robert_Rieger-2025-002.19532e93-300x400.jpg 300w, https:\/\/www.matrix4design.com\/wp-content\/uploads\/2025\/11\/Flos-Luce_Sferica-PH_Robert_Rieger-2025-002.19532e93-696x928.jpg 696w, https:\/\/www.matrix4design.com\/wp-content\/uploads\/2025\/11\/Flos-Luce_Sferica-PH_Robert_Rieger-2025-002.19532e93-1068x1424.jpg 1068w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><figcaption id=\"caption-attachment-116936\" class=\"wp-caption-text\">Luce Sferica \u00a9 Robert Rieger<\/figcaption><\/figure>\n<p><strong>Luce Sferica<\/strong> ricerca la delicatezza, evocando &#8220;le gocce di pioggia che si aggrappano a un filo, o una bolla di sapone soffiata da un bambino&#8221;. La lampada \u00e8 formata da un corpo orizzontale altamente tecnico in <strong>alluminio estruso lucidato<\/strong>, su cui alloggiano due strisce LED per emissioni luminose verso l&#8217;alto e verso il basso. Un innovativo <strong>dimmer touch<\/strong> a un\u2019estremit\u00e0 permette di selezionare e regolare individualmente l\u2019emissione superiore o inferiore. Attorno a questo asse tecnico &#8220;scivolano&#8221; sfere di vetro leggero e trasparente, ciascuna di circa 180 mm di diametro, realizzate con l&#8217;antica arte del vetro soffiato. Il risultato \u00e8 un corpo luminoso &#8220;etereo e dalla presenza magica&#8221;. Luce Sferica \u00e8 disponibile in tre lunghezze modulari (S1, S2, S3), da 1,650 m (8 sfere) a 2,70 m (10 sfere).<\/p>\n<figure id=\"attachment_116937\" aria-describedby=\"caption-attachment-116937\" style=\"width: 1200px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-116937\" src=\"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2025\/11\/Flos-Luce_Cilindrica-PH_Robert_Rieger-2025-011.015526d2.jpg\" alt=\"\" width=\"1200\" height=\"1600\" srcset=\"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2025\/11\/Flos-Luce_Cilindrica-PH_Robert_Rieger-2025-011.015526d2.jpg 1200w, https:\/\/www.matrix4design.com\/wp-content\/uploads\/2025\/11\/Flos-Luce_Cilindrica-PH_Robert_Rieger-2025-011.015526d2-225x300.jpg 225w, https:\/\/www.matrix4design.com\/wp-content\/uploads\/2025\/11\/Flos-Luce_Cilindrica-PH_Robert_Rieger-2025-011.015526d2-768x1024.jpg 768w, https:\/\/www.matrix4design.com\/wp-content\/uploads\/2025\/11\/Flos-Luce_Cilindrica-PH_Robert_Rieger-2025-011.015526d2-1152x1536.jpg 1152w, https:\/\/www.matrix4design.com\/wp-content\/uploads\/2025\/11\/Flos-Luce_Cilindrica-PH_Robert_Rieger-2025-011.015526d2-150x200.jpg 150w, https:\/\/www.matrix4design.com\/wp-content\/uploads\/2025\/11\/Flos-Luce_Cilindrica-PH_Robert_Rieger-2025-011.015526d2-300x400.jpg 300w, https:\/\/www.matrix4design.com\/wp-content\/uploads\/2025\/11\/Flos-Luce_Cilindrica-PH_Robert_Rieger-2025-011.015526d2-696x928.jpg 696w, https:\/\/www.matrix4design.com\/wp-content\/uploads\/2025\/11\/Flos-Luce_Cilindrica-PH_Robert_Rieger-2025-011.015526d2-1068x1424.jpg 1068w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><figcaption id=\"caption-attachment-116937\" class=\"wp-caption-text\">Luce Cilindrica \u00a9 Robert Rieger<\/figcaption><\/figure>\n<p><strong>Luce Cilindrica<\/strong> rappresenta una variante complementare che condivide la stessa identica tecnologia di base. L\u2019innovazione risiede nella geometria: in luogo delle sfere si trovano moduli eterei di forma cilindrica. Questa versione si sviluppa dal progetto <em>Luce Orizzontale<\/em>, concepito inizialmente per l&#8217;atrio della Bourse de Commerce &#8211; Fondazione Pinault, in relazione all&#8217;architettura di Tadao Ando. Per conferire una &#8220;delicatezza pressoch\u00e9 irreale&#8221;, Luce Cilindrica utilizza <strong>vetro borosilicato<\/strong> per assicurare massima trasparenza, leggerezza e resistenza, in contrasto con il vetro colato del progetto originale.<\/p>\n<p>Entrambe le lampade (disponibili nelle stesse misure S1, S2, S3) emettono una luce diffusa, efficiente e gentile (LED 2700K, CRI 95), ideali per illuminare grandi tavoli in contesti privati, <em>hospitality<\/em> o ambienti museali, creando un suggestivo effetto scenografico se installate in file parallele. I due progetti esprimono appieno la poetica e la ricerca estetica di Bouroullec, utilizzando la tecnica per creare la magia e la raffinatezza tipiche dell\u2019illuminazione Flos.<\/p>\n<p>&nbsp;<\/p>\n\t\t<div style=\"clear:both\"><\/div>\n\t\t<div class=\"psgal_wrap\">\n\t\t\t<div id=\"psgal_116934_1\" data-psgal_id=\"116934_1\" data-psgal_container_id=\"container_116934_1\" data-psgal_thumbnail_width=\"164\" data-psgal_use_masonary=\"1\" class=\"psgal-inline psgal gallery-columns-3 gallery-size-thumbnail use_masonry_1 show_captions_\" itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\">\n\t\t\t\t\t\t\t\t\t\t<figure class=\"msnry_items\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" style=\"width:164px;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2025\/11\/Flos-Luce_Cilindrica-PH_Robert_Rieger-2025-006.cfe9eeaf.jpg\" itemprop=\"contentUrl\" data-size=\"1600x1200\" data-caption=\"Luce Cilindrica \u00a9 Robert Rieger\" style=\"height:154px;\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"msnry_thumb\" src=\"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2025\/11\/Flos-Luce_Cilindrica-PH_Robert_Rieger-2025-006.cfe9eeaf-328x328.jpg\" itemprop=\"thumbnail\" alt=\"\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"photoswipe-gallery-caption\" style=\"display:none;\">Luce Cilindrica \u00a9 Robert Rieger<\/figcaption>\n\n\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t\t<figure class=\"msnry_items\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" style=\"width:164px;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2025\/11\/Flos-Luce_Cilindrica-PH_Robert_Rieger-2025-008.b5f1bcb9.jpg\" itemprop=\"contentUrl\" data-size=\"1200x1600\" data-caption=\"Luce Cilindrica \u00a9 Robert Rieger\" style=\"height:154px;\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"msnry_thumb\" src=\"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2025\/11\/Flos-Luce_Cilindrica-PH_Robert_Rieger-2025-008.b5f1bcb9-328x328.jpg\" itemprop=\"thumbnail\" alt=\"\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"photoswipe-gallery-caption\" style=\"display:none;\">Luce Cilindrica \u00a9 Robert Rieger<\/figcaption>\n\n\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t\t<figure class=\"msnry_items\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" style=\"width:164px;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2025\/11\/Flos-Luce_Sferica-PH_Robert_Rieger-2025-001.ccc4de5c.jpg\" itemprop=\"contentUrl\" data-size=\"1600x1200\" data-caption=\"Luce Sferica \u00a9 Robert Rieger\" style=\"height:154px;\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"msnry_thumb\" src=\"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2025\/11\/Flos-Luce_Sferica-PH_Robert_Rieger-2025-001.ccc4de5c-328x328.jpg\" itemprop=\"thumbnail\" alt=\"\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"photoswipe-gallery-caption\" style=\"display:none;\">Luce Sferica \u00a9 Robert Rieger<\/figcaption>\n\n\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t\t<figure class=\"msnry_items\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" style=\"width:164px;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2025\/11\/Flos-Luce_Sferica-PH_Robert_Rieger-2025-002.19532e93-1.jpg\" itemprop=\"contentUrl\" data-size=\"1200x1600\" data-caption=\"Luce Sferica \u00a9 Robert Rieger\" style=\"height:154px;\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"msnry_thumb\" src=\"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2025\/11\/Flos-Luce_Sferica-PH_Robert_Rieger-2025-002.19532e93-1-328x328.jpg\" itemprop=\"thumbnail\" alt=\"\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"photoswipe-gallery-caption\" style=\"display:none;\">Luce Sferica \u00a9 Robert Rieger<\/figcaption>\n\n\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div style='clear:both'><\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Ronan Bouroullec firma per Flos due nuove lampade a sospensione modulari, Luce Sferica e Luce Cilindrica, uscite nel 2025. Questi progetti non sono semplici corpi illuminanti, ma vere e proprie esaltazioni della bellezza delle cose semplici e della magia ottenuta attraverso la raffinatezza tecnica. Il design mira a unire la bellezza poetica del prodotto [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":116935,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[366,418,368],"tags":[],"class_list":["post-116934","post","type-post","status-publish","format-standard","has-post-thumbnail","category-design","category-design-home","category-featured"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Flos e Ronan Bouroullec: la poesia della luce sospesa tra sfera e cilindro<\/title>\n<meta name=\"description\" content=\"Ronan Bouroullec firma per Flos due nuove lampade a sospensione modulari, Luce Sferica e Luce Cilindrica, uscite nel 2025.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.matrix4design.com\/it\/design\/flos-e-ronan-bouroullec-la-poesia-della-luce-sospesa-tra-sfera-e-cilindro\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Flos e Ronan Bouroullec: la poesia della luce sospesa tra sfera e cilindro\" \/>\n<meta property=\"og:description\" content=\"Ronan Bouroullec firma per Flos due nuove lampade a sospensione modulari, Luce Sferica e Luce Cilindrica, uscite nel 2025.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.matrix4design.com\/it\/design\/flos-e-ronan-bouroullec-la-poesia-della-luce-sospesa-tra-sfera-e-cilindro\/\" \/>\n<meta property=\"og:site_name\" content=\"Matrix4Design\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/matrix4designmagazine\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-21T07:00:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2025\/11\/Flos-Luce_Sferica-PH_Robert_Rieger-2025-010.3ad70c5f.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.matrix4design.com\\\/it\\\/design\\\/flos-e-ronan-bouroullec-la-poesia-della-luce-sospesa-tra-sfera-e-cilindro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.matrix4design.com\\\/it\\\/design\\\/flos-e-ronan-bouroullec-la-poesia-della-luce-sospesa-tra-sfera-e-cilindro\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.matrix4design.com\\\/it\\\/#\\\/schema\\\/person\\\/b2b6dd48f9d6892ca224742379951fa1\"},\"headline\":\"Flos e Ronan Bouroullec: la poesia della luce sospesa tra sfera e cilindro\",\"datePublished\":\"2025-11-21T07:00:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.matrix4design.com\\\/it\\\/design\\\/flos-e-ronan-bouroullec-la-poesia-della-luce-sospesa-tra-sfera-e-cilindro\\\/\"},\"wordCount\":376,\"publisher\":{\"@id\":\"https:\\\/\\\/www.matrix4design.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.matrix4design.com\\\/it\\\/design\\\/flos-e-ronan-bouroullec-la-poesia-della-luce-sospesa-tra-sfera-e-cilindro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.matrix4design.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Flos-Luce_Sferica-PH_Robert_Rieger-2025-010.3ad70c5f.jpg\",\"articleSection\":[\"Design\",\"Design home\",\"Featured\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.matrix4design.com\\\/it\\\/design\\\/flos-e-ronan-bouroullec-la-poesia-della-luce-sospesa-tra-sfera-e-cilindro\\\/\",\"url\":\"https:\\\/\\\/www.matrix4design.com\\\/it\\\/design\\\/flos-e-ronan-bouroullec-la-poesia-della-luce-sospesa-tra-sfera-e-cilindro\\\/\",\"name\":\"Flos e Ronan Bouroullec: la poesia della luce sospesa tra sfera e cilindro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.matrix4design.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.matrix4design.com\\\/it\\\/design\\\/flos-e-ronan-bouroullec-la-poesia-della-luce-sospesa-tra-sfera-e-cilindro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.matrix4design.com\\\/it\\\/design\\\/flos-e-ronan-bouroullec-la-poesia-della-luce-sospesa-tra-sfera-e-cilindro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.matrix4design.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Flos-Luce_Sferica-PH_Robert_Rieger-2025-010.3ad70c5f.jpg\",\"datePublished\":\"2025-11-21T07:00:26+00:00\",\"description\":\"Ronan Bouroullec firma per Flos due nuove lampade a sospensione modulari, Luce Sferica e Luce Cilindrica, uscite nel 2025.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.matrix4design.com\\\/it\\\/design\\\/flos-e-ronan-bouroullec-la-poesia-della-luce-sospesa-tra-sfera-e-cilindro\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.matrix4design.com\\\/it\\\/design\\\/flos-e-ronan-bouroullec-la-poesia-della-luce-sospesa-tra-sfera-e-cilindro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.matrix4design.com\\\/it\\\/design\\\/flos-e-ronan-bouroullec-la-poesia-della-luce-sospesa-tra-sfera-e-cilindro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.matrix4design.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Flos-Luce_Sferica-PH_Robert_Rieger-2025-010.3ad70c5f.jpg\",\"contentUrl\":\"https:\\\/\\\/www.matrix4design.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Flos-Luce_Sferica-PH_Robert_Rieger-2025-010.3ad70c5f.jpg\",\"width\":1600,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.matrix4design.com\\\/it\\\/design\\\/flos-e-ronan-bouroullec-la-poesia-della-luce-sospesa-tra-sfera-e-cilindro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.matrix4design.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Flos e Ronan Bouroullec: la poesia della luce sospesa tra sfera e cilindro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.matrix4design.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.matrix4design.com\\\/it\\\/\",\"name\":\"Matrix4Design\",\"description\":\"Digital architecture and design b2b magazine\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.matrix4design.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.matrix4design.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.matrix4design.com\\\/it\\\/#organization\",\"name\":\"Matrix4Design\",\"url\":\"https:\\\/\\\/www.matrix4design.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.matrix4design.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.matrix4design.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo_matrix4design.png\",\"contentUrl\":\"https:\\\/\\\/www.matrix4design.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo_matrix4design.png\",\"width\":804,\"height\":114,\"caption\":\"Matrix4Design\"},\"image\":{\"@id\":\"https:\\\/\\\/www.matrix4design.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/matrix4designmagazine\\\/\",\"https:\\\/\\\/www.instagram.com\\\/matrix4designmagazine\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCtuhSSrP3MOO_URZgv8mQ1A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.matrix4design.com\\\/it\\\/#\\\/schema\\\/person\\\/b2b6dd48f9d6892ca224742379951fa1\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.matrix4design.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/logo_M4D_2023-96x96.jpg\",\"url\":\"https:\\\/\\\/www.matrix4design.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/logo_M4D_2023-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/www.matrix4design.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/logo_M4D_2023-96x96.jpg\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.matrix4design.com\\\/it\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Flos e Ronan Bouroullec: la poesia della luce sospesa tra sfera e cilindro","description":"Ronan Bouroullec firma per Flos due nuove lampade a sospensione modulari, Luce Sferica e Luce Cilindrica, uscite nel 2025.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.matrix4design.com\/it\/design\/flos-e-ronan-bouroullec-la-poesia-della-luce-sospesa-tra-sfera-e-cilindro\/","og_locale":"it_IT","og_type":"article","og_title":"Flos e Ronan Bouroullec: la poesia della luce sospesa tra sfera e cilindro","og_description":"Ronan Bouroullec firma per Flos due nuove lampade a sospensione modulari, Luce Sferica e Luce Cilindrica, uscite nel 2025.","og_url":"https:\/\/www.matrix4design.com\/it\/design\/flos-e-ronan-bouroullec-la-poesia-della-luce-sospesa-tra-sfera-e-cilindro\/","og_site_name":"Matrix4Design","article_publisher":"https:\/\/www.facebook.com\/matrix4designmagazine\/","article_published_time":"2025-11-21T07:00:26+00:00","og_image":[{"width":1600,"height":1200,"url":"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2025\/11\/Flos-Luce_Sferica-PH_Robert_Rieger-2025-010.3ad70c5f.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.matrix4design.com\/it\/design\/flos-e-ronan-bouroullec-la-poesia-della-luce-sospesa-tra-sfera-e-cilindro\/#article","isPartOf":{"@id":"https:\/\/www.matrix4design.com\/it\/design\/flos-e-ronan-bouroullec-la-poesia-della-luce-sospesa-tra-sfera-e-cilindro\/"},"author":{"name":"Redazione","@id":"https:\/\/www.matrix4design.com\/it\/#\/schema\/person\/b2b6dd48f9d6892ca224742379951fa1"},"headline":"Flos e Ronan Bouroullec: la poesia della luce sospesa tra sfera e cilindro","datePublished":"2025-11-21T07:00:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.matrix4design.com\/it\/design\/flos-e-ronan-bouroullec-la-poesia-della-luce-sospesa-tra-sfera-e-cilindro\/"},"wordCount":376,"publisher":{"@id":"https:\/\/www.matrix4design.com\/it\/#organization"},"image":{"@id":"https:\/\/www.matrix4design.com\/it\/design\/flos-e-ronan-bouroullec-la-poesia-della-luce-sospesa-tra-sfera-e-cilindro\/#primaryimage"},"thumbnailUrl":"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2025\/11\/Flos-Luce_Sferica-PH_Robert_Rieger-2025-010.3ad70c5f.jpg","articleSection":["Design","Design home","Featured"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.matrix4design.com\/it\/design\/flos-e-ronan-bouroullec-la-poesia-della-luce-sospesa-tra-sfera-e-cilindro\/","url":"https:\/\/www.matrix4design.com\/it\/design\/flos-e-ronan-bouroullec-la-poesia-della-luce-sospesa-tra-sfera-e-cilindro\/","name":"Flos e Ronan Bouroullec: la poesia della luce sospesa tra sfera e cilindro","isPartOf":{"@id":"https:\/\/www.matrix4design.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.matrix4design.com\/it\/design\/flos-e-ronan-bouroullec-la-poesia-della-luce-sospesa-tra-sfera-e-cilindro\/#primaryimage"},"image":{"@id":"https:\/\/www.matrix4design.com\/it\/design\/flos-e-ronan-bouroullec-la-poesia-della-luce-sospesa-tra-sfera-e-cilindro\/#primaryimage"},"thumbnailUrl":"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2025\/11\/Flos-Luce_Sferica-PH_Robert_Rieger-2025-010.3ad70c5f.jpg","datePublished":"2025-11-21T07:00:26+00:00","description":"Ronan Bouroullec firma per Flos due nuove lampade a sospensione modulari, Luce Sferica e Luce Cilindrica, uscite nel 2025.","breadcrumb":{"@id":"https:\/\/www.matrix4design.com\/it\/design\/flos-e-ronan-bouroullec-la-poesia-della-luce-sospesa-tra-sfera-e-cilindro\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.matrix4design.com\/it\/design\/flos-e-ronan-bouroullec-la-poesia-della-luce-sospesa-tra-sfera-e-cilindro\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.matrix4design.com\/it\/design\/flos-e-ronan-bouroullec-la-poesia-della-luce-sospesa-tra-sfera-e-cilindro\/#primaryimage","url":"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2025\/11\/Flos-Luce_Sferica-PH_Robert_Rieger-2025-010.3ad70c5f.jpg","contentUrl":"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2025\/11\/Flos-Luce_Sferica-PH_Robert_Rieger-2025-010.3ad70c5f.jpg","width":1600,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/www.matrix4design.com\/it\/design\/flos-e-ronan-bouroullec-la-poesia-della-luce-sospesa-tra-sfera-e-cilindro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.matrix4design.com\/it\/"},{"@type":"ListItem","position":2,"name":"Flos e Ronan Bouroullec: la poesia della luce sospesa tra sfera e cilindro"}]},{"@type":"WebSite","@id":"https:\/\/www.matrix4design.com\/it\/#website","url":"https:\/\/www.matrix4design.com\/it\/","name":"Matrix4Design","description":"Digital architecture and design b2b magazine","publisher":{"@id":"https:\/\/www.matrix4design.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.matrix4design.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.matrix4design.com\/it\/#organization","name":"Matrix4Design","url":"https:\/\/www.matrix4design.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.matrix4design.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2020\/04\/logo_matrix4design.png","contentUrl":"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2020\/04\/logo_matrix4design.png","width":804,"height":114,"caption":"Matrix4Design"},"image":{"@id":"https:\/\/www.matrix4design.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/matrix4designmagazine\/","https:\/\/www.instagram.com\/matrix4designmagazine\/","https:\/\/www.youtube.com\/channel\/UCtuhSSrP3MOO_URZgv8mQ1A"]},{"@type":"Person","@id":"https:\/\/www.matrix4design.com\/it\/#\/schema\/person\/b2b6dd48f9d6892ca224742379951fa1","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2023\/01\/logo_M4D_2023-96x96.jpg","url":"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2023\/01\/logo_M4D_2023-96x96.jpg","contentUrl":"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2023\/01\/logo_M4D_2023-96x96.jpg","caption":"Redazione"},"url":"https:\/\/www.matrix4design.com\/it\/author\/redazione\/"}]}},"_links":{"self":[{"href":"https:\/\/www.matrix4design.com\/it\/wp-json\/wp\/v2\/posts\/116934","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.matrix4design.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.matrix4design.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.matrix4design.com\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.matrix4design.com\/it\/wp-json\/wp\/v2\/comments?post=116934"}],"version-history":[{"count":3,"href":"https:\/\/www.matrix4design.com\/it\/wp-json\/wp\/v2\/posts\/116934\/revisions"}],"predecessor-version":[{"id":116944,"href":"https:\/\/www.matrix4design.com\/it\/wp-json\/wp\/v2\/posts\/116934\/revisions\/116944"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.matrix4design.com\/it\/wp-json\/wp\/v2\/media\/116935"}],"wp:attachment":[{"href":"https:\/\/www.matrix4design.com\/it\/wp-json\/wp\/v2\/media?parent=116934"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.matrix4design.com\/it\/wp-json\/wp\/v2\/categories?post=116934"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.matrix4design.com\/it\/wp-json\/wp\/v2\/tags?post=116934"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}