{"id":118536,"date":"2026-02-17T11:00:33","date_gmt":"2026-02-17T10:00:33","guid":{"rendered":"https:\/\/www.matrix4design.com\/?p=118536"},"modified":"2026-02-12T09:37:51","modified_gmt":"2026-02-12T08:37:51","slug":"il-nuovo-volto-del-piazzale-degli-umiliati-a-lissone-firmato-da-land","status":"publish","type":"post","link":"https:\/\/www.matrix4design.com\/it\/architettura\/il-nuovo-volto-del-piazzale-degli-umiliati-a-lissone-firmato-da-land\/","title":{"rendered":"Il nuovo volto del Piazzale degli Umiliati a Lissone firmato da Land"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>In un\u2019epoca in cui la rigenerazione urbana deve necessariamente rispondere alle urgenze del cambiamento climatico, la trasformazione delle grandi superfici impermeabili diventa il banco di prova per l\u2019architettura del paesaggio contemporanea. Il progetto di riqualificazione del <strong>Piazzale degli Umiliati a Lissone<\/strong>, curato dal team di <a href=\"https:\/\/www.landsrl.com\/en\/\" target=\"_blank\" rel=\"noopener\"><strong>LAND<\/strong><\/a>, si inserisce esattamente in questo solco: <strong>convertire un\u2019area asfaltata di 2 ettari in una nuova centralit\u00e0 urbana dove natura e socialit\u00e0 tornano a convergere<\/strong>.<\/p>\n<p>Attualmente configurato come un\u2019ampia distesa di asfalto destinata principalmente al mercato settimanale e alla sosta, il piazzale \u00e8 dunque destinato a mutare pelle. L\u2019intervento nello specifico mira a restituire lo spazio alla collettivit\u00e0, trasformandolo in un <strong>luogo identitario e multifunzionale<\/strong>, fruibile quotidianamente e non solo in occasione di eventi specifici.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-118538 size-full\" src=\"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2026\/02\/LAND_Piazza-Umiliati-Taglio-Verde-1-scaled.jpg\" alt=\"piazzale\" width=\"2560\" height=\"1810\" srcset=\"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2026\/02\/LAND_Piazza-Umiliati-Taglio-Verde-1-scaled.jpg 2560w, https:\/\/www.matrix4design.com\/wp-content\/uploads\/2026\/02\/LAND_Piazza-Umiliati-Taglio-Verde-1-300x212.jpg 300w, https:\/\/www.matrix4design.com\/wp-content\/uploads\/2026\/02\/LAND_Piazza-Umiliati-Taglio-Verde-1-1024x724.jpg 1024w, https:\/\/www.matrix4design.com\/wp-content\/uploads\/2026\/02\/LAND_Piazza-Umiliati-Taglio-Verde-1-768x543.jpg 768w, https:\/\/www.matrix4design.com\/wp-content\/uploads\/2026\/02\/LAND_Piazza-Umiliati-Taglio-Verde-1-1536x1086.jpg 1536w, https:\/\/www.matrix4design.com\/wp-content\/uploads\/2026\/02\/LAND_Piazza-Umiliati-Taglio-Verde-1-2048x1448.jpg 2048w, https:\/\/www.matrix4design.com\/wp-content\/uploads\/2026\/02\/LAND_Piazza-Umiliati-Taglio-Verde-1-150x106.jpg 150w, https:\/\/www.matrix4design.com\/wp-content\/uploads\/2026\/02\/LAND_Piazza-Umiliati-Taglio-Verde-1-696x492.jpg 696w, https:\/\/www.matrix4design.com\/wp-content\/uploads\/2026\/02\/LAND_Piazza-Umiliati-Taglio-Verde-1-1068x755.jpg 1068w, https:\/\/www.matrix4design.com\/wp-content\/uploads\/2026\/02\/LAND_Piazza-Umiliati-Taglio-Verde-1-1920x1358.jpg 1920w, https:\/\/www.matrix4design.com\/wp-content\/uploads\/2026\/02\/LAND_Piazza-Umiliati-Taglio-Verde-1-1800x1273.jpg 1800w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/p>\n<p>Cuore della proposta \u00e8 il cosiddetto \u201c<strong>Taglio Verde<\/strong>\u201d: una <strong>fascia paesaggistica continua che attraversa l\u2019area,<\/strong> fungendo da spina dorsale per l\u2019interazione sociale. All\u2019interno di questo sistema si articoleranno: <strong>10.000 mq di nuovi percorsi pedonali <\/strong>dedicati al gioco, allo sport all\u2019aperto e alla mobilit\u00e0 dolce; <strong>3.500 mq di aree verdi<\/strong>, arricchite dalla piantumazione di 128 nuovi alberi per garantire zone d\u2019ombra e mitigazione termica; e <strong>un nuovo padiglione multifunzionale<\/strong>, che integrer\u00e0 le funzioni civiche dello spazio.<\/p>\n<p>L\u2019aspetto tecnico pi\u00f9 innovativo risiede nella <strong>gestione delle risorse idriche<\/strong>: il piazzale adotter\u00e0 soluzioni avanzate di drenaggio urbano (SuDS). Attraverso sistemi di accumulo e laminazione dell&#8217;acqua piovana, il progetto mira a ridurre la portata di picco scaricata nella fognatura, aumentando la resilienza del territorio di fronte agli eventi meteorologici estremi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; In un\u2019epoca in cui la rigenerazione urbana deve necessariamente rispondere alle urgenze del cambiamento climatico, la trasformazione delle grandi superfici impermeabili diventa il banco di prova per l\u2019architettura del paesaggio contemporanea. Il progetto di riqualificazione del Piazzale degli Umiliati a Lissone, curato dal team di LAND, si inserisce esattamente in questo solco: convertire un\u2019area [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":118537,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[367,417,368],"tags":[],"class_list":["post-118536","post","type-post","status-publish","format-standard","has-post-thumbnail","category-architettura","category-architettura-home","category-featured"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il nuovo volto del Piazzale degli Umiliati a Lissone firmato da Land<\/title>\n<meta name=\"description\" content=\"In un\u2019epoca in cui la rigenerazione urbana deve necessariamente rispondere alle urgenze del cambiamento climatico, la trasformazione delle grandi superfici impermeabili diventa il banco di prova per l\u2019architettura del paesaggio contemporanea. Il progetto di riqualificazione del Piazzale degli Umiliati a Lissone, curato dal team di LAND, si inserisce esattamente in questo solco.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.matrix4design.com\/it\/architettura\/il-nuovo-volto-del-piazzale-degli-umiliati-a-lissone-firmato-da-land\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il nuovo volto del Piazzale degli Umiliati a Lissone firmato da Land\" \/>\n<meta property=\"og:description\" content=\"In un\u2019epoca in cui la rigenerazione urbana deve necessariamente rispondere alle urgenze del cambiamento climatico, la trasformazione delle grandi superfici impermeabili diventa il banco di prova per l\u2019architettura del paesaggio contemporanea. Il progetto di riqualificazione del Piazzale degli Umiliati a Lissone, curato dal team di LAND, si inserisce esattamente in questo solco.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.matrix4design.com\/it\/architettura\/il-nuovo-volto-del-piazzale-degli-umiliati-a-lissone-firmato-da-land\/\" \/>\n<meta property=\"og:site_name\" content=\"Matrix4Design\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/matrix4designmagazine\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-17T10:00:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2026\/02\/LAND_Piazza-Umiliati-Taglio-Verde-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1810\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.matrix4design.com\\\/it\\\/architettura\\\/il-nuovo-volto-del-piazzale-degli-umiliati-a-lissone-firmato-da-land\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.matrix4design.com\\\/it\\\/architettura\\\/il-nuovo-volto-del-piazzale-degli-umiliati-a-lissone-firmato-da-land\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.matrix4design.com\\\/it\\\/#\\\/schema\\\/person\\\/b2b6dd48f9d6892ca224742379951fa1\"},\"headline\":\"Il nuovo volto del Piazzale degli Umiliati a Lissone firmato da Land\",\"datePublished\":\"2026-02-17T10:00:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.matrix4design.com\\\/it\\\/architettura\\\/il-nuovo-volto-del-piazzale-degli-umiliati-a-lissone-firmato-da-land\\\/\"},\"wordCount\":264,\"publisher\":{\"@id\":\"https:\\\/\\\/www.matrix4design.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.matrix4design.com\\\/it\\\/architettura\\\/il-nuovo-volto-del-piazzale-degli-umiliati-a-lissone-firmato-da-land\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.matrix4design.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/LAND_Piazza-Umiliati-Taglio-Verde-scaled.jpg\",\"articleSection\":[\"Architettura\",\"Architettura home\",\"Featured\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.matrix4design.com\\\/it\\\/architettura\\\/il-nuovo-volto-del-piazzale-degli-umiliati-a-lissone-firmato-da-land\\\/\",\"url\":\"https:\\\/\\\/www.matrix4design.com\\\/it\\\/architettura\\\/il-nuovo-volto-del-piazzale-degli-umiliati-a-lissone-firmato-da-land\\\/\",\"name\":\"Il nuovo volto del Piazzale degli Umiliati a Lissone firmato da Land\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.matrix4design.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.matrix4design.com\\\/it\\\/architettura\\\/il-nuovo-volto-del-piazzale-degli-umiliati-a-lissone-firmato-da-land\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.matrix4design.com\\\/it\\\/architettura\\\/il-nuovo-volto-del-piazzale-degli-umiliati-a-lissone-firmato-da-land\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.matrix4design.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/LAND_Piazza-Umiliati-Taglio-Verde-scaled.jpg\",\"datePublished\":\"2026-02-17T10:00:33+00:00\",\"description\":\"In un\u2019epoca in cui la rigenerazione urbana deve necessariamente rispondere alle urgenze del cambiamento climatico, la trasformazione delle grandi superfici impermeabili diventa il banco di prova per l\u2019architettura del paesaggio contemporanea. Il progetto di riqualificazione del Piazzale degli Umiliati a Lissone, curato dal team di LAND, si inserisce esattamente in questo solco.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.matrix4design.com\\\/it\\\/architettura\\\/il-nuovo-volto-del-piazzale-degli-umiliati-a-lissone-firmato-da-land\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.matrix4design.com\\\/it\\\/architettura\\\/il-nuovo-volto-del-piazzale-degli-umiliati-a-lissone-firmato-da-land\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.matrix4design.com\\\/it\\\/architettura\\\/il-nuovo-volto-del-piazzale-degli-umiliati-a-lissone-firmato-da-land\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.matrix4design.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/LAND_Piazza-Umiliati-Taglio-Verde-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.matrix4design.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/LAND_Piazza-Umiliati-Taglio-Verde-scaled.jpg\",\"width\":2560,\"height\":1810,\"caption\":\"Piazzale\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.matrix4design.com\\\/it\\\/architettura\\\/il-nuovo-volto-del-piazzale-degli-umiliati-a-lissone-firmato-da-land\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.matrix4design.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il nuovo volto del Piazzale degli Umiliati a Lissone firmato da Land\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.matrix4design.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.matrix4design.com\\\/it\\\/\",\"name\":\"Matrix4Design\",\"description\":\"Digital architecture and design b2b magazine\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.matrix4design.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.matrix4design.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.matrix4design.com\\\/it\\\/#organization\",\"name\":\"Matrix4Design\",\"url\":\"https:\\\/\\\/www.matrix4design.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.matrix4design.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.matrix4design.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo_matrix4design.png\",\"contentUrl\":\"https:\\\/\\\/www.matrix4design.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo_matrix4design.png\",\"width\":804,\"height\":114,\"caption\":\"Matrix4Design\"},\"image\":{\"@id\":\"https:\\\/\\\/www.matrix4design.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/matrix4designmagazine\\\/\",\"https:\\\/\\\/www.instagram.com\\\/matrix4designmagazine\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCtuhSSrP3MOO_URZgv8mQ1A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.matrix4design.com\\\/it\\\/#\\\/schema\\\/person\\\/b2b6dd48f9d6892ca224742379951fa1\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.matrix4design.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/logo_M4D_2023-96x96.jpg\",\"url\":\"https:\\\/\\\/www.matrix4design.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/logo_M4D_2023-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/www.matrix4design.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/logo_M4D_2023-96x96.jpg\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.matrix4design.com\\\/it\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il nuovo volto del Piazzale degli Umiliati a Lissone firmato da Land","description":"In un\u2019epoca in cui la rigenerazione urbana deve necessariamente rispondere alle urgenze del cambiamento climatico, la trasformazione delle grandi superfici impermeabili diventa il banco di prova per l\u2019architettura del paesaggio contemporanea. Il progetto di riqualificazione del Piazzale degli Umiliati a Lissone, curato dal team di LAND, si inserisce esattamente in questo solco.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.matrix4design.com\/it\/architettura\/il-nuovo-volto-del-piazzale-degli-umiliati-a-lissone-firmato-da-land\/","og_locale":"it_IT","og_type":"article","og_title":"Il nuovo volto del Piazzale degli Umiliati a Lissone firmato da Land","og_description":"In un\u2019epoca in cui la rigenerazione urbana deve necessariamente rispondere alle urgenze del cambiamento climatico, la trasformazione delle grandi superfici impermeabili diventa il banco di prova per l\u2019architettura del paesaggio contemporanea. Il progetto di riqualificazione del Piazzale degli Umiliati a Lissone, curato dal team di LAND, si inserisce esattamente in questo solco.","og_url":"https:\/\/www.matrix4design.com\/it\/architettura\/il-nuovo-volto-del-piazzale-degli-umiliati-a-lissone-firmato-da-land\/","og_site_name":"Matrix4Design","article_publisher":"https:\/\/www.facebook.com\/matrix4designmagazine\/","article_published_time":"2026-02-17T10:00:33+00:00","og_image":[{"width":2560,"height":1810,"url":"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2026\/02\/LAND_Piazza-Umiliati-Taglio-Verde-scaled.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.matrix4design.com\/it\/architettura\/il-nuovo-volto-del-piazzale-degli-umiliati-a-lissone-firmato-da-land\/#article","isPartOf":{"@id":"https:\/\/www.matrix4design.com\/it\/architettura\/il-nuovo-volto-del-piazzale-degli-umiliati-a-lissone-firmato-da-land\/"},"author":{"name":"Redazione","@id":"https:\/\/www.matrix4design.com\/it\/#\/schema\/person\/b2b6dd48f9d6892ca224742379951fa1"},"headline":"Il nuovo volto del Piazzale degli Umiliati a Lissone firmato da Land","datePublished":"2026-02-17T10:00:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.matrix4design.com\/it\/architettura\/il-nuovo-volto-del-piazzale-degli-umiliati-a-lissone-firmato-da-land\/"},"wordCount":264,"publisher":{"@id":"https:\/\/www.matrix4design.com\/it\/#organization"},"image":{"@id":"https:\/\/www.matrix4design.com\/it\/architettura\/il-nuovo-volto-del-piazzale-degli-umiliati-a-lissone-firmato-da-land\/#primaryimage"},"thumbnailUrl":"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2026\/02\/LAND_Piazza-Umiliati-Taglio-Verde-scaled.jpg","articleSection":["Architettura","Architettura home","Featured"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.matrix4design.com\/it\/architettura\/il-nuovo-volto-del-piazzale-degli-umiliati-a-lissone-firmato-da-land\/","url":"https:\/\/www.matrix4design.com\/it\/architettura\/il-nuovo-volto-del-piazzale-degli-umiliati-a-lissone-firmato-da-land\/","name":"Il nuovo volto del Piazzale degli Umiliati a Lissone firmato da Land","isPartOf":{"@id":"https:\/\/www.matrix4design.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.matrix4design.com\/it\/architettura\/il-nuovo-volto-del-piazzale-degli-umiliati-a-lissone-firmato-da-land\/#primaryimage"},"image":{"@id":"https:\/\/www.matrix4design.com\/it\/architettura\/il-nuovo-volto-del-piazzale-degli-umiliati-a-lissone-firmato-da-land\/#primaryimage"},"thumbnailUrl":"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2026\/02\/LAND_Piazza-Umiliati-Taglio-Verde-scaled.jpg","datePublished":"2026-02-17T10:00:33+00:00","description":"In un\u2019epoca in cui la rigenerazione urbana deve necessariamente rispondere alle urgenze del cambiamento climatico, la trasformazione delle grandi superfici impermeabili diventa il banco di prova per l\u2019architettura del paesaggio contemporanea. Il progetto di riqualificazione del Piazzale degli Umiliati a Lissone, curato dal team di LAND, si inserisce esattamente in questo solco.","breadcrumb":{"@id":"https:\/\/www.matrix4design.com\/it\/architettura\/il-nuovo-volto-del-piazzale-degli-umiliati-a-lissone-firmato-da-land\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.matrix4design.com\/it\/architettura\/il-nuovo-volto-del-piazzale-degli-umiliati-a-lissone-firmato-da-land\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.matrix4design.com\/it\/architettura\/il-nuovo-volto-del-piazzale-degli-umiliati-a-lissone-firmato-da-land\/#primaryimage","url":"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2026\/02\/LAND_Piazza-Umiliati-Taglio-Verde-scaled.jpg","contentUrl":"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2026\/02\/LAND_Piazza-Umiliati-Taglio-Verde-scaled.jpg","width":2560,"height":1810,"caption":"Piazzale"},{"@type":"BreadcrumbList","@id":"https:\/\/www.matrix4design.com\/it\/architettura\/il-nuovo-volto-del-piazzale-degli-umiliati-a-lissone-firmato-da-land\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.matrix4design.com\/it\/"},{"@type":"ListItem","position":2,"name":"Il nuovo volto del Piazzale degli Umiliati a Lissone firmato da Land"}]},{"@type":"WebSite","@id":"https:\/\/www.matrix4design.com\/it\/#website","url":"https:\/\/www.matrix4design.com\/it\/","name":"Matrix4Design","description":"Digital architecture and design b2b magazine","publisher":{"@id":"https:\/\/www.matrix4design.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.matrix4design.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.matrix4design.com\/it\/#organization","name":"Matrix4Design","url":"https:\/\/www.matrix4design.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.matrix4design.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2020\/04\/logo_matrix4design.png","contentUrl":"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2020\/04\/logo_matrix4design.png","width":804,"height":114,"caption":"Matrix4Design"},"image":{"@id":"https:\/\/www.matrix4design.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/matrix4designmagazine\/","https:\/\/www.instagram.com\/matrix4designmagazine\/","https:\/\/www.youtube.com\/channel\/UCtuhSSrP3MOO_URZgv8mQ1A"]},{"@type":"Person","@id":"https:\/\/www.matrix4design.com\/it\/#\/schema\/person\/b2b6dd48f9d6892ca224742379951fa1","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2023\/01\/logo_M4D_2023-96x96.jpg","url":"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2023\/01\/logo_M4D_2023-96x96.jpg","contentUrl":"https:\/\/www.matrix4design.com\/wp-content\/uploads\/2023\/01\/logo_M4D_2023-96x96.jpg","caption":"Redazione"},"url":"https:\/\/www.matrix4design.com\/it\/author\/redazione\/"}]}},"_links":{"self":[{"href":"https:\/\/www.matrix4design.com\/it\/wp-json\/wp\/v2\/posts\/118536","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.matrix4design.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.matrix4design.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.matrix4design.com\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.matrix4design.com\/it\/wp-json\/wp\/v2\/comments?post=118536"}],"version-history":[{"count":3,"href":"https:\/\/www.matrix4design.com\/it\/wp-json\/wp\/v2\/posts\/118536\/revisions"}],"predecessor-version":[{"id":118550,"href":"https:\/\/www.matrix4design.com\/it\/wp-json\/wp\/v2\/posts\/118536\/revisions\/118550"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.matrix4design.com\/it\/wp-json\/wp\/v2\/media\/118537"}],"wp:attachment":[{"href":"https:\/\/www.matrix4design.com\/it\/wp-json\/wp\/v2\/media?parent=118536"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.matrix4design.com\/it\/wp-json\/wp\/v2\/categories?post=118536"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.matrix4design.com\/it\/wp-json\/wp\/v2\/tags?post=118536"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}